{"id":595,"date":"2022-01-31T22:27:03","date_gmt":"2022-01-31T21:27:03","guid":{"rendered":"https:\/\/blog.predictanalyse.com\/?p=595"},"modified":"2023-02-09T14:07:39","modified_gmt":"2023-02-09T13:07:39","slug":"la-medecine-5p-le-p-de-prevention","status":"publish","type":"post","link":"https:\/\/blog.predictanalyse.com\/index.php\/2022\/01\/31\/la-medecine-5p-le-p-de-prevention\/","title":{"rendered":"La m\u00e9decine \u00ab 5P \u00bb : le \u00ab P \u00bb de Pr\u00e9vention"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\" id=\"introduction\">Introduction<\/h4>\n\n\n\n<p>La m\u00e9decine aujourd\u2019hui cherche \u00e0 basculer vers des prises en charge dites \u00ab&nbsp;5P&nbsp;\u00bb&nbsp;: <strong>pr\u00e9ventives, personnalis\u00e9es, participatives, pr\u00e9dictives et ayant fait leurs preuves<\/strong>. Ceci est une excellente avanc\u00e9e qui nous donne des grands axes de directions et qui va, si correctement appliqu\u00e9e, am\u00e9liorer les plans de soin pour les individus. Malheureusement, ces grandes id\u00e9es sont souvent mal comprises ou mal employ\u00e9es. Comme personne n\u2019ose s\u2019attaquer aux m\u00e9thodes utilis\u00e9es, personne ne remet en question le paradigme actuel, pourtant vou\u00e9, en partie, \u00e0 l\u2019\u00e9chec. Peut-\u00eatre que nous n\u2019avons tout simplement pas les bonnes approches\u2026 Voyons point par point, \u00ab&nbsp;5P&nbsp;\u00bb par \u00ab&nbsp;5P&nbsp;\u00bb, les <strong>limites <\/strong>actuelles.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"la-prevention-arrive-bel-et-bien-dans-notre-quotidien\">La pr\u00e9vention arrive bel et bien dans notre quotidien<\/h4>\n\n\n\n<p>Depuis un certain temps maintenant nous avons compris que la meilleure fa\u00e7on de prendre en charge une personne est de faire de la pr\u00e9vention. La <strong>strat\u00e9gie interventionniste<\/strong> qui consiste \u00e0 traiter un probl\u00e8me d\u00e9j\u00e0 d\u00e9clar\u00e9 ne manque pas seulement d\u2019efficacit\u00e9 mais passe souvent \u00e0 c\u00f4t\u00e9 de la r\u00e9elle probl\u00e9matique. Il est facile \u00e0 comprendre qu\u2019il ne faut pas attendre d\u2019avoir les dents qui tombent <a href=\"https:\/\/blog.predictanalyse.com\/index.php\/2021\/10\/07\/se-brosser-les-dents-pour-moins-de-douleurs-au-dos\/\">pour commencer \u00e0 se les brosser<\/a>. <\/p>\n\n\n\n<p>De la m\u00eame fa\u00e7on, il ne faut pas attendre d\u2019avoir une maladie cardiaque pour commencer \u00e0 pratiquer du sport. Bien que la notion passe plus difficilement en ce qui concerne les <strong>Troubles Musculo-Squelettiques (TMS) ou les Risques Psycho-Sociaux (RPS)<\/strong>, le concept reste le m\u00eame et les strat\u00e9gies de traitement changent. Nous y arrivons. Lentement.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/predictanalyse.com\/produit\/analyse-des-risques\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-1170x581.png\" alt=\"\" class=\"wp-image-1074\" width=\"610\" height=\"303\" srcset=\"https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-1170x581.png 1170w, https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-768x381.png 768w, https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-1536x762.png 1536w, https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-845x419.png 845w, https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-585x290.png 585w, https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-520x258.png 520w, https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2-1310x650.png 1310w, https:\/\/blog.predictanalyse.com\/wp-content\/uploads\/2022\/10\/PREDICTA-2.png 1620w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/><\/a><\/figure><\/div>\n\n\n<h4 class=\"wp-block-heading\" id=\"a-t-elle-un-vrai-impact\">A-t-elle un vrai impact&nbsp;?<\/h4>\n\n\n\n<p>Si la graine de l\u2019id\u00e9e est bien plant\u00e9e, les m\u00e9thodes utilis\u00e9es pour l\u2019accomplir sont encore <strong>d\u00e9plorables<\/strong>. De nombreux dispositifs de pr\u00e9vention ont d\u00e9j\u00e0 \u00e9t\u00e9 mis en place ces derni\u00e8res d\u00e9cennies, et pourtant, les courbes ne semblent pas s\u2019infl\u00e9chir. <strong>Les TMS et les RPS sont install\u00e9s dans notre quotidien<\/strong> et cela a l\u2019air de ne plus surprendre personne, comme si aucune solution viable n\u2019existait. Comme si ces troubles devaient partager notre quotidien. Comme s\u2019ils \u00e9taient semblables \u00e0 un jour de pluie&nbsp;: in\u00e9luctable. Pourquoi&nbsp;? <a href=\"https:\/\/blog.predictanalyse.com\/index.php\/2021\/11\/29\/les-experts-ont-tort-et-les-articles-sont-faux\/\">N\u2019a-t-on pas d\u2019experts comp\u00e9tents<\/a>&nbsp;? La pr\u00e9vention est-elle inefficace dans certains cas&nbsp;? Pense-t-on que nos m\u00e9thodes sont efficaces et que le taux de TMS\/RPS est aujourd\u2019hui au plus bas&nbsp;?<\/p>\n\n\n\n<p>Si nous sommes si s\u00fbrs que la pr\u00e9vention a toute sa place dans les plans de sant\u00e9, c\u2019est \u00e0 plus forte raison. C\u2019est en effet le but ultime&nbsp;: atteindre une <strong>pr\u00e9vention efficace et g\u00e9n\u00e9ralis\u00e9e<\/strong>. Pour cela les 4 autres \u00ab&nbsp;P&nbsp;\u00bb doivent l\u2019assister, et ils peinent \u00e0 r\u00e9ussir car ils sont employ\u00e9s avec des m\u00e9thodes parfois tr\u00e8s contestables. Commen\u00e7ons par \u00e9tudier les probl\u00e9matiques d\u2019une sant\u00e9 \u00ab&nbsp;<strong><a href=\"https:\/\/blog.predictanalyse.com\/index.php\/2022\/01\/31\/la-medecine-5p-le-p-de-personnalisee\/\" target=\"_blank\" rel=\"noreferrer noopener\">Personnalis\u00e9e&nbsp;<\/a><\/strong>\u00bb.<\/p>\n\n\n\n<p>Voir les probl\u00e8mes dans : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le \u00ab\u00a0P\u00a0\u00bb de <strong><strong><a href=\"https:\/\/blog.predictanalyse.com\/index.php\/2022\/01\/31\/la-medecine-5p-le-p-de-personnalisee\/\" target=\"_blank\" rel=\"noreferrer noopener\">Personnalis\u00e9e&nbsp;<\/a><\/strong><\/strong><\/li>\n\n\n\n<li>Le \u00ab\u00a0P\u00a0\u00bb de <strong><a href=\"https:\/\/blog.predictanalyse.com\/index.php\/2022\/01\/31\/la-medecine-5p-le-p-de-participative\/\" target=\"_blank\" rel=\"noreferrer noopener\">Participative<\/a><\/strong><\/li>\n\n\n\n<li>Le \u00ab\u00a0P\u00a0\u00bb de <strong><a href=\"https:\/\/blog.predictanalyse.com\/index.php\/2022\/01\/31\/la-medecine-5p-le-p-de-preuves\/\" target=\"_blank\" rel=\"noreferrer noopener\">Preuves<\/a><\/strong><\/li>\n\n\n\n<li>Le \u00ab\u00a0P\u00a0\u00bb de <strong><a href=\"https:\/\/blog.predictanalyse.com\/index.php\/2022\/01\/31\/la-medecine-5p-le-p-de-predictive\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00e9dictive<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Sources : <br><\/mark><a href=\"https:\/\/gnius.esante.gouv.fr\/fr\/strategie-dacceleration-sante-numerique\">https:\/\/gnius.esante.gouv.fr\/fr\/strategie-dacceleration-sante-numerique<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00e9decine \u00ab 5P \u00bb pr\u00e9sente la pr\u00e9vention comme l&rsquo;axe th\u00e9rapeutique majeur \u00e0 g\u00e9n\u00e9raliser aupr\u00e8s de la population. Mais comment s&rsquo;y prendre ?<\/p>\n","protected":false},"author":1,"featured_media":666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[16,9],"tags":[],"class_list":["post-595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prevention","category-sante"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/posts\/595"}],"collection":[{"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/comments?post=595"}],"version-history":[{"count":9,"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/posts\/595\/revisions"}],"predecessor-version":[{"id":1095,"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/posts\/595\/revisions\/1095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/media\/666"}],"wp:attachment":[{"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/media?parent=595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/categories?post=595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.predictanalyse.com\/index.php\/wp-json\/wp\/v2\/tags?post=595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}